{"id":1,"count":1,"description":"","link":"https:\/\/tempeltje.inwerker.dev\/en\/category\/ongecategoriseerd\/","name":"Ongecategoriseerd","slug":"ongecategoriseerd","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/tempeltje.inwerker.dev\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tempeltje.inwerker.dev\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tempeltje.inwerker.dev\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tempeltje.inwerker.dev\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}